{"id":125000000133,"date":"2018-10-01T02:24:19","date_gmt":"2018-10-01T02:24:19","guid":{"rendered":"https:\/\/kidsrkids.com\/west-houston\/parent-area\/newsletter-2\/"},"modified":"2026-05-04T15:34:01","modified_gmt":"2026-05-04T15:34:01","slug":"newsletter","status":"publish","type":"page","link":"https:\/\/kidsrkids.com\/west-houston\/parent-area\/newsletter\/","title":{"rendered":"Newsletter"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":165,"featured_media":0,"parent":125000000314,"menu_order":6,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-125000000133","page","type-page","status-publish","hentry","visibility_tax-mixed","editability_tax-editable","required_tax-notrequired","syndication_tax-syndicated"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Newsletter - West Houston<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kidsrkids.com\/west-houston\/parent-area\/newsletter\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Newsletter - West Houston\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kidsrkids.com\/west-houston\/parent-area\/newsletter\/\" \/>\n<meta property=\"og:site_name\" content=\"West Houston\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-04T15:34:01+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Newsletter - West Houston","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kidsrkids.com\/west-houston\/parent-area\/newsletter\/","og_locale":"en_US","og_type":"article","og_title":"Newsletter - West Houston","og_url":"https:\/\/kidsrkids.com\/west-houston\/parent-area\/newsletter\/","og_site_name":"West Houston","article_modified_time":"2026-05-04T15:34:01+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kidsrkids.com\/west-houston\/parent-area\/newsletter\/","url":"https:\/\/kidsrkids.com\/west-houston\/parent-area\/newsletter\/","name":"Newsletter - West Houston","isPartOf":{"@id":"https:\/\/kidsrkids.com\/west-houston\/#website"},"datePublished":"2018-10-01T02:24:19+00:00","dateModified":"2026-05-04T15:34:01+00:00","breadcrumb":{"@id":"https:\/\/kidsrkids.com\/west-houston\/parent-area\/newsletter\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kidsrkids.com\/west-houston\/parent-area\/newsletter\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kidsrkids.com\/west-houston\/parent-area\/newsletter\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kidsrkids.com\/west-houston\/"},{"@type":"ListItem","position":2,"name":"Parent Area","item":"https:\/\/kidsrkids.com\/west-houston\/parent-area\/"},{"@type":"ListItem","position":3,"name":"Newsletter"}]},{"@type":"WebSite","@id":"https:\/\/kidsrkids.com\/west-houston\/#website","url":"https:\/\/kidsrkids.com\/west-houston\/","name":"West Houston","description":"Just another Kids &#039;R&#039; Kids site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kidsrkids.com\/west-houston\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/kidsrkids.com\/west-houston\/wp-json\/wp\/v2\/pages\/125000000133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kidsrkids.com\/west-houston\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kidsrkids.com\/west-houston\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kidsrkids.com\/west-houston\/wp-json\/wp\/v2\/users\/165"}],"replies":[{"embeddable":true,"href":"https:\/\/kidsrkids.com\/west-houston\/wp-json\/wp\/v2\/comments?post=125000000133"}],"version-history":[{"count":0,"href":"https:\/\/kidsrkids.com\/west-houston\/wp-json\/wp\/v2\/pages\/125000000133\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/kidsrkids.com\/west-houston\/wp-json\/wp\/v2\/pages\/125000000314"}],"wp:attachment":[{"href":"https:\/\/kidsrkids.com\/west-houston\/wp-json\/wp\/v2\/media?parent=125000000133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}